{"id":51662,"date":"2025-12-02T01:00:00","date_gmt":"2025-12-02T00:00:00","guid":{"rendered":"https:\/\/www.snowtrex.de\/magazin\/?p=51662"},"modified":"2026-05-12T14:05:40","modified_gmt":"2026-05-12T12:05:40","slug":"tour-de-ski","status":"publish","type":"post","link":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/","title":{"rendered":"Tour de Ski 2025\/2026 \u2013 Alle Infos zum Highlight der Skilanglauf-Saison"},"content":{"rendered":"<p><strong>Auf kaum ein zweites Rennen im Langlauf-Weltcup passt das Motto: &#8222;Dies ist ein Marathon, kein Sprint&#8220; so gut wie auf die Tour de Ski. Rund um Neujahr geben die Topathleten des nordischen Skisports hier jedes Jahr auf mehreren Etappen alles. In der letzten Saison demonstrierten dies eindrucksvoll Johannes H\u00f8sflot Kl\u00e6bo und Therese Johaug (beide Norwegen). Sie kr\u00f6nten sich am Ende des mittlerweile weltber\u00fchmten Anstiegs zum K\u00f6nig und zur K\u00f6nigin der Langl\u00e4ufer. Grund genug f\u00fcr <a href=\"https:\/\/www.snowtrex.de\/\" target=\"_blank\" rel=\"noopener\">SnowTrex<\/a> einmal die Faszination &#8222;Tour de Ski&#8220; zu erkl\u00e4ren und die Sportler vorzustellen, die diesem Wettkampf in der Vergangenheit ihren Stempel aufgedr\u00fcckt haben.<\/strong><\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-52476 size-Artikelbild_gro\u00df\" title=\"Bei der Tour de Ski treten die Athletinnen und Athleten in fast allen Einzelrennformaten an. Gelaufen wird dabei sowohl in der klassischen Technik als auch im Freistil.\" src=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-729x486.jpg\" alt=\"Bei der Tour de Ski treten die Athletinnen und Athleten in fast allen Einzelrennformaten an. Gelaufen wird dabei sowohl in der klassischen Technik als auch im Freistil.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-729x486.jpg 729w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-468x312.jpg 468w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-300x200.jpg 300w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-999x666.jpg 999w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-645x430.jpg 645w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-552x368.jpg 552w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-405x270.jpg 405w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-336x224.jpg 336w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-276x184.jpg 276w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-234x156.jpg 234w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-192x128.jpg 192w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-120x80.jpg 120w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc-774x516.jpg 774w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"52476\">\u00a9 Pierre Teyssot\/Shutterstock<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Bei der Tour de Ski treten die Athletinnen und Athleten in fast allen Einzelrennformaten an. Gelaufen wird dabei sowohl in der klassischen Technik als auch im Freistil.<\/div>\n         <\/div > \n<div class=\"tt-table-of-content\">\n                <span class=\"tt-icon-circle-up tt-table-of-content-button\"><\/span><\/p>\n<div class=\"tt-table-of-content-caption\">\n                    Inhaltsverzeichnis\n                <\/div>\n<div class=\"tt-table-of-content-body\">\n                    <a href=\"#die-etappen-der-tour-de-ski-20252026-im-\u00dcberblick\"><span class=\"layer-0\">Die Etappen der Tour de Ski 2025\/2026 im \u00dcberblick<\/span><\/a><a href=\"#die-geschichte-der-tour-de-ski\"><span class=\"layer-0\">Die Geschichte der Tour de Ski<\/span><\/a><a href=\"#so-l\u00e4uft-die-tour-de-ski\"><span class=\"layer-0\">So l\u00e4uft die Tour de Ski<\/span><\/a><a href=\"#die-erfolgreichsten-athletinnen-der-tour-de-ski\"><span class=\"layer-0\">Die erfolgreichsten Athletinnen der Tour de Ski<\/span><\/a><a href=\"#die-erfolgreichsten-athleten-der-tour-de-ski\"><span class=\"layer-0\">Die erfolgreichsten Athleten der Tour de Ski<\/span><\/a><a href=\"#faqs-zur-tour-de-ski\"><span class=\"layer-0\">FAQs zur Tour de Ski<\/span><\/a>\n                 <\/div>\n<\/p><\/div>\n<hr>\n<h2 id=\"die-etappen-der-tour-de-ski-20252026-im-\u00dcberblick\">Die Etappen der Tour de Ski 2025\/2026 im \u00dcberblick<\/h2>\n\n<table id=\"tablepress-121\" class=\"tablepress tablepress-id-121\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><strong>Datum<\/strong><\/th><th class=\"column-2\"><strong>Ort<\/strong><\/th><th class=\"column-3\"><strong>Disziplin<\/strong><\/th><th class=\"column-4\"><strong>Laufstil<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">28.12.2025<\/td><td class=\"column-2\">Toblach (Italien)<\/td><td class=\"column-3\">Sprint<\/td><td class=\"column-4\">Freistil<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">29.12.2025<\/td><td class=\"column-2\">Toblach (Italien)<\/td><td class=\"column-3\">10 km Einzel<\/td><td class=\"column-4\">klassisch<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">31.12.2025<\/td><td class=\"column-2\">Toblach (Italien)<\/td><td class=\"column-3\">5 km Massenstart<\/td><td class=\"column-4\">Freistil<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">01.01.2026<\/td><td class=\"column-2\">Toblach (Italien)<\/td><td class=\"column-3\">15 km Verfolgung<\/td><td class=\"column-4\">klassisch<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">03.01.2026<\/td><td class=\"column-2\">Val di Fiemme (Italien)<\/td><td class=\"column-3\">Sprint<\/td><td class=\"column-4\">klassisch<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">04.01.2026<\/td><td class=\"column-2\">Val di Fiemme (Italien)<\/td><td class=\"column-3\">10 km Final Climb<\/td><td class=\"column-4\">Freistil<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-121 from cache -->\n<div class=\"lyte-wrapper\" title=\"Therese Johaug ties Kowalczyk with four Tour de Ski overall wins | FIS Cross Country World Cup 24-25\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_i8Z-Z1pi6wU\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2Fi8Z-Z1pi6wU%2Fhqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/i8Z-Z1pi6wU\" \/><meta itemprop=\"duration\" content=\"PT2M27S\" \/><meta itemprop=\"uploadDate\" content=\"2025-01-05T16:11:16Z\" \/><\/div><div id=\"lyte_i8Z-Z1pi6wU\" data-src=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2Fi8Z-Z1pi6wU%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Therese Johaug ties Kowalczyk with four Tour de Ski overall wins | FIS Cross Country World Cup 24-25<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"http:\/\/youtu.be\/i8Z-Z1pi6wU\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=http%3A%2F%2Fi.ytimg.com%2Fvi%2Fi8Z-Z1pi6wU%2F0.jpg\" alt=\"Therese Johaug ties Kowalczyk with four Tour de Ski overall wins | FIS Cross Country World Cup 24-25\" width=\"853\" height=\"460\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><meta itemprop=\"description\" content=\"Thank you for watching, don\u2019t forget to like, subscribe and hit the bell if you want to be kept up to date with all our latest content! Instagram \ud83d\udcf8 http:\/\/instagram.com\/fiscrosscountry Facebook \ud83d\udc4d https:\/\/www.facebook.com\/fiscrosscountry X \ud83d\udc24 https:\/\/twitter.com\/fiscrosscountry International Ski Federation: as the governing body of international skiing and snowboarding, FIS manages the Olympic disciplines of Alpine Skiing, Cross-Country Skiing, Ski Jumping, Nordic Combined, Freestyle Skiing and Snowboarding, including setting the international competition rules.\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><br\/><span class=\"lyte_disclaimer\">Bitte beachten Sie zudem, dass durch die Nutzung unserer Dienste und der Einbindung der YouTube API Services die <a href=\"https:\/\/www.youtube.com\/t\/terms\">YouTube Terms of Service<\/a> sowie die <a href=\"https:\/\/developers.google.com\/youtube\/terms\/api-services-terms-of-service-emea-de\">YouTube API Services Terms<\/a> gelten und Ihre Nutzung unserer Website als Zustimmung zu diesen Bedingungen betrachtet wird.<\/span><\/div><\/p>\n<p><em data-renderer-mark=\"true\">\u2192 Alpen-Auszeit planen und die besten Angebote in <a href=\"https:\/\/www.snowtrex.de\/suchen_buchen.html?destinationId=12140&amp;destinationUuId=&amp;destination=Toblach\" target=\"_blank\" rel=\"noopener\">Toblach<\/a> oder im <a href=\"https:\/\/www.snowtrex.de\/suchen_buchen.html?destinationId=3873&amp;destinationUuId=4028815c9670032a0196c37d4f2e515a\" target=\"_blank\" rel=\"noopener\">Fleimstal<\/a> bei SnowTrex finden<\/em><\/p>\n<h2 id=\"die-geschichte-der-tour-de-ski\">Die Geschichte der Tour de Ski<\/h2>\n<p>Die Art und Weise, wie es die Tour de Ski in der Saison 2006\/07 in den Weltcupkalender der Skilangl\u00e4ufer schaffte, kann als kurios bezeichnet werden. Zwei Jahre zuvor, im Sp\u00e4tsommer 2004, trafen sich zwei M\u00e4nner in einer Sauna in Norwegen. Wenige Wochen zuvor war in Paris das weltweit ber\u00fchmteste Radrennen, die Tour de France, geendet. Und deswegen diskutierten die beiden Herren nun in der Badewanne. Namentlich J\u00fcrg Capol und seinen Gastgeber, den Norweger Vegard Ulvang. Schlie\u00dflich hatten der mehrfache Langlauf-Olympiasieger und der Langlauf-Chef des Internationalen Skiverbandes (FIS) eine Idee. Die Einf\u00fchrung eines mehrt\u00e4gigen Etappenrennens im Schnee.<\/p>\n<p>Die Vorteile einer solchen Tour waren f\u00fcr beide nach eigener Aussage direkt offensichtlich. Denn um die komplettesten Langl\u00e4ufer unter den Athleten aus dem Weltcup zu k\u00fcren, sollten die nicht nur jeweils in ihren Spezialdisziplinen wie Distanzrennen oder Sprints antreten m\u00fcssen. Wie bei der Tour de France, bei der die teilnehmenden Radprofis \u00fcber drei Wochen Tag f\u00fcr Tag ihre Vielseitigkeit beweisen m\u00fcssen, sah das Duo dies auch f\u00fcr die Langl\u00e4ufer vor. Statt Flachetappen, Bergank\u00fcnften und Zeitfahren w\u00fcrden f\u00fcr sie dagegen bei der Tour de Ski Sprint-, Verfolgungs- und Massenstartrennen sowohl im klassischen Stil als auch im Freistil auf dem Plan stehen.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-52477 size-Artikelbild_gro\u00df\" title=\"Auf vielen Etappen der Tour de Ski f\u00e4llt die Entscheidung in der Loipe meist erst im Schlussspurt auf der Zielgeraden.\" src=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-729x486.jpg\" alt=\"Auf vielen Etappen der Tour de Ski f\u00e4llt die Entscheidung in der Loipe meist erst im Schlussspurt auf der Zielgeraden.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-729x486.jpg 729w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-468x312.jpg 468w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-300x200.jpg 300w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-999x666.jpg 999w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-645x430.jpg 645w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-552x368.jpg 552w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-405x270.jpg 405w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-336x224.jpg 336w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-276x184.jpg 276w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-234x156.jpg 234w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-192x128.jpg 192w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-120x80.jpg 120w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26512_shutterstock_1605515626-scr-774x516.jpg 774w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"52477\">\u00a9 Pierre Teyssot\/Shutterstock<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Auf vielen Etappen der Tour de Ski f\u00e4llt die Entscheidung in der Loipe meist erst im Schlussspurt auf der Zielgeraden.<\/div>\n         <\/div > \n<p>Der Vorschlag, den Capol auch an die offiziellen Gremien der FIS weiterleitete, kam dort so gut an, dass der Weltverband das mehrt\u00e4gige Etappenrennen schlie\u00dflich f\u00fcr die Saison 2006\/07 in den Weltcupkalender aufnahm. Allerdings war die folgende Planung f\u00fcr die erste Ausgabe der Tour de Ski etwas holprig. Zum einen fiel eine weitere Idee von Ulvang direkt durch. So wollte er n\u00e4mlich nicht nur in den Alpen ein Tour-Projekt auf die Beine stellen. Sondern auch in der Barents Region zwischen Norwegen, Schweden, Finnland und Russland.<\/p>\n<p>Und auch in \u00d6sterreich und der Schweiz hielt sich die Begeisterung f\u00fcr das Etappenrennen der Langl\u00e4ufer zun\u00e4chst in Grenzen. Weil sich f\u00fcr 2006 dort keine Veranstalter fanden, sollte die Tour zun\u00e4chst in Tschechien in Nov\u00e9 M\u011bsto starten. Doch wegen Schneemangels reisten die Athleten kurzfristig direkt nach M\u00fcnchen. Dort war f\u00fcr den 31. Dezember 2006 eigentlich die 3. Etappe angesetzt. Statt eines normalen Sprints wurde die aber zum historischen Prolog der allerersten Tour de Ski.<\/p>\n<h2 id=\"so-l\u00e4uft-die-tour-de-ski\">So l\u00e4uft die Tour de Ski<\/h2>\n<p>Damit die Motivation der Langl\u00e4ufer, die Tour de Ski auch zu Ende zu laufen, hoch bleibt, gibt es f\u00fcr die Etappen an sich zun\u00e4chst keine Weltcuppunkte. Hier z\u00e4hlt jeweils nur die erlaufene Zeit. Sie wird nach jeder Etappe auf die Gesamtzeit addiert. \u00dcber Zwischensprints in den einzelnen Rennen gibt es f\u00fcr die Schnellsten noch Bonussekunden und dementsprechend weitere zeitliche Vorteile gegen\u00fcber der Konkurrenz. Mit der gr\u00f6\u00dfte Anreiz f\u00fcr eine gute Platzierung im Endklassement der Tour de Ski sind aber vor allem die Preisgelder. So d\u00fcrfen die Sieger nach der letzten Etappe nicht nur das ikonische gelbe Leibchen der Gesamtf\u00fchrenden behalten. Ihnen stehen auch jeweils 85.000 Schweizer Franken zu. Insgesamt werden im Rahmen der Tour 2024\/2025 \u00fcber 770.000 Schweizer Franken ausgesch\u00fcttet. Das Preisgeld ist nach Platzierung aufgestaffelt, sodass sich selbst die Athleten auf dem 20. Platz noch \u00fcber 1.000 Schweizer Franken freuen d\u00fcrfen.<\/p>\n<p>Und die Weltcuppunkte, die bei der Tour de Ski dann doch noch verteilt werden, gibt es als gro\u00dfen Batzen f\u00fcr die Endplatzierung in der Gesamtwertung. Das bedeutet f\u00fcr den Sieger mit der schnellsten Gesamtlaufzeit satte 300 Punkte f\u00fcr den Kampf um den Gesamtweltcup. Zum Vergleich: F\u00fcr den Sieg bei einem normalen Einzelrennen im Weltcup gibt es 100 Punkte. Und auch die Pl\u00e4tze 2 bis 50 der Tour de Ski-Gesamtwertung gehen nicht leer aus. In absteigender Reihenfolge werden die platzierten Athleten hier ebenfalls mit entsprechenden Weltcuppunkten belohnt.<\/p>\n<div class=\"lyte-wrapper\" title=\"Johannes H. Klaebo equals Cologna with four Tour de Ski titles | FIS Cross Country World Cup 24-25\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_lJoIezsSIZQ\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FlJoIezsSIZQ%2Fhqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/lJoIezsSIZQ\" \/><meta itemprop=\"duration\" content=\"PT2M37S\" \/><meta itemprop=\"uploadDate\" content=\"2025-01-05T14:53:08Z\" \/><\/div><div id=\"lyte_lJoIezsSIZQ\" data-src=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FlJoIezsSIZQ%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">Johannes H. Klaebo equals Cologna with four Tour de Ski titles | FIS Cross Country World Cup 24-25<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"http:\/\/youtu.be\/lJoIezsSIZQ\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snowtrex.de\/magazin\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=http%3A%2F%2Fi.ytimg.com%2Fvi%2FlJoIezsSIZQ%2F0.jpg\" alt=\"Johannes H. Klaebo equals Cologna with four Tour de Ski titles | FIS Cross Country World Cup 24-25\" width=\"853\" height=\"460\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><meta itemprop=\"description\" content=\"Thank you for watching, don\u2019t forget to like, subscribe and hit the bell if you want to be kept up to date with all our latest content! Instagram \ud83d\udcf8 http:\/\/instagram.com\/fiscrosscountry Facebook \ud83d\udc4d https:\/\/www.facebook.com\/fiscrosscountry X \ud83d\udc24 https:\/\/twitter.com\/fiscrosscountry International Ski Federation: as the governing body of international skiing and snowboarding, FIS manages the Olympic disciplines of Alpine Skiing, Cross-Country Skiing, Ski Jumping, Nordic Combined, Freestyle Skiing and Snowboarding, including setting the international competition rules.\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><br\/><span class=\"lyte_disclaimer\">Bitte beachten Sie zudem, dass durch die Nutzung unserer Dienste und der Einbindung der YouTube API Services die <a href=\"https:\/\/www.youtube.com\/t\/terms\">YouTube Terms of Service<\/a> sowie die <a href=\"https:\/\/developers.google.com\/youtube\/terms\/api-services-terms-of-service-emea-de\">YouTube API Services Terms<\/a> gelten und Ihre Nutzung unserer Website als Zustimmung zu diesen Bedingungen betrachtet wird.<\/span><\/div><\/p>\n<p>Der Ablauf der Wettk\u00e4mpfe der Tour de Ski variiert von Jahr zu Jahr. Zum einen gibt es nicht, wie bei der Tour de France \u00fcblich, eine festgelegte Anzahl von Etappen. Die Zahl der Teilst\u00fccke schwankte bislang immer zwischen 6 und 9 Rennen. Um den Reisestress zu minimieren, versuchen die Veranstalter der Tour de Ski sich auch meistens auf drei Austragungsorte festzulegen, in denen die Etappen dann stattfinden. In den Anfangsjahren wurde die Tour immer mit einem Prolog er\u00f6ffnet. Hier gingen die Athletinnen und Athleten einzeln und im Abstand von 30 Sekunden auf eine knapp 5 km lange Loipenrunde.<\/p>\n<p>Nach den ersten Tour-Ausgaben wurde der Prolog aber durch ein Sprintrennen ersetzt. In diesem Format treten immer sechs Langl\u00e4ufer in einem Heat gegeneinander an. Hier ziehen dann die beiden Athleten in die n\u00e4chste Runde ein, die als Erstes nach knapp 1,5 km die Ziellinie \u00fcberqueren. Bevor im Finale der besten Sechs der Sieger ermittelt wird.<\/p>\n<p>Um den Gedanken der beiden &#8222;V\u00e4ter&#8220; der Tour de Ski, J\u00fcrg Capol und Vegard Ulvang, aufrechtzuerhalten, teilen sich die Etappen aber gr\u00f6\u00dftenteils in Distanzrennen auf. So soll die Vielseitigkeit der Langl\u00e4ufer belohnt werden. Wie im Weltcup wird auf den Tagesabschnitten auch in der klassischen Technik oder im Freistil gelaufen. Meist \u00fcber die \u00fcblichen Distanzen wie 10 km oder 15 km. Dazu kommen noch weitere Sprintrennen. Die ultimative Herausforderung f\u00fcr die Langl\u00e4uferinnen und Langl\u00e4ufer ist dagegen die Schlussetappe. Sie gibt es so kein zweites Mal im Weltcupkalender. Seit der ersten Tour de Ski steht hier n\u00e4mlich jedes Jahr der sogenannte Final Climb im <a href=\"https:\/\/www.snowtrex.de\/italien\/predazzo\/skigebiet.html\" target=\"_blank\" rel=\"noopener\">Val di Fiemme<\/a> an.<\/p>\n<p>Die Gesamtdistanz des Teilst\u00fccks liegt mit 10 km zwar noch im absoluten Rahmen f\u00fcr die Profis. Allerdings sind die letzten 3,6 km einzigartig. Statt wie zuvor in einer normalen Loipe geht es hier n\u00e4mlich eine Skipiste hoch. Aus dem Tal bis zur Alpe Cermis m\u00fcssen die Teilnehmer dabei noch einmal an die absolute Leistungsgrenze gehen. Und gr\u00f6\u00dftenteils auch dar\u00fcber hinaus. An der steilsten Stelle m\u00fcssen die Langl\u00e4ufer 28 Prozent Gef\u00e4lle bezwingen. Um die Belastung in Grenzen zu halten, indem die Athleten mehrfach parallel zum Hang laufen k\u00f6nnen, sind auf der Strecke auch Kurven eingebaut.<\/p>\n<h2 id=\"die-erfolgreichsten-athletinnen-der-tour-de-ski\">Die erfolgreichsten Athletinnen der Tour de Ski<\/h2>\n\n<table id=\"tablepress-119\" class=\"tablepress tablepress-id-119\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><strong>Gesamtsiege<\/strong><br \/>\n<\/th><th class=\"column-2\"><strong>Name<\/strong><br \/>\n<\/th><th class=\"column-3\"><strong>Nationalit\u00e4t<\/strong><br \/>\n<\/th><th class=\"column-4\"><strong>Tour de Ski<\/strong><br \/>\n<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">Justyna Kowalczyk<\/td><td class=\"column-3\">Polen<\/td><td class=\"column-4\">2009\/10, 2010\/11, 2011\/12, 2012\/13<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">Therese Johaug<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2013\/14, 2016, 2019\/20, 2024\/25<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Virpi Kuitunen<\/td><td class=\"column-3\">Finnland<\/td><td class=\"column-4\">2006\/07, 2008\/09<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Heidi Weng<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2016\/17, 2017\/18<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Jessica Diggins<\/td><td class=\"column-3\">USA<\/td><td class=\"column-4\">2021, 2023\/24<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Charlotte Kalla<\/td><td class=\"column-3\">Schweden<\/td><td class=\"column-4\">2007\/08<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Marit Bj\u00f8rgen<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2015<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Ingvild Flugstad \u00d8stberg<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2018\/19<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Natalya Nepryayeva<\/td><td class=\"column-3\">Russland<\/td><td class=\"column-4\">2021\/22<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Frida Karlsson<\/td><td class=\"column-3\">Schweden<\/td><td class=\"column-4\">2022\/23<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-119 from cache -->\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-56166 size-Artikelbild_gro\u00df\" title=\"Die Norwegerin Therese Johaug geh\u00f6rt mit vier Gesamtsiegen zu einer der erfolgreichsten Langl\u00e4uferinnen in der Geschichte der Tour de Ski.\" src=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-729x486.jpg\" alt=\"Die Norwegerin Therese Johaug geh\u00f6rt mit vier Gesamtsiegen zu einer der erfolgreichsten Langl\u00e4uferinnen in der Geschichte der Tour de Ski.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-729x486.jpg 729w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-468x312.jpg 468w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-300x200.jpg 300w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-999x666.jpg 999w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-645x430.jpg 645w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-552x368.jpg 552w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-405x270.jpg 405w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-336x224.jpg 336w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-276x184.jpg 276w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-234x156.jpg 234w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-192x128.jpg 192w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-120x80.jpg 120w, https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26511_shutterstock_1605515608-scr-774x516.jpg 774w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"56166\">\u00a9 Pierre Teyssot\/Shutterstock<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Die Norwegerin Therese Johaug geh\u00f6rt mit vier Gesamtsiegen zu einer der erfolgreichsten Langl\u00e4uferinnen in der Geschichte der Tour de Ski.<\/div>\n         <\/div > \n<h2 id=\"die-erfolgreichsten-athleten-der-tour-de-ski\">Die erfolgreichsten Athleten der Tour de Ski<\/h2>\n\n<table id=\"tablepress-120\" class=\"tablepress tablepress-id-120\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><strong>Gesamtsiege<\/strong><br \/>\n<\/th><th class=\"column-2\"><strong>Name<\/strong><br \/>\n<\/th><th class=\"column-3\"><strong>Nationalit\u00e4t<\/strong><br \/>\n<\/th><th class=\"column-4\"><strong>Tour de Ski<\/strong><br \/>\n<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">Dario Cologna<\/td><td class=\"column-3\">Schweiz<\/td><td class=\"column-4\">2008\/09, 2010\/11, 2011\/12, 2017\/18<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">Johannes H\u00f8sflot Kl\u00e6bo<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2018\/19, 2021\/22, 2022\/23, 2024\/25<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Luk\u00e1\u0161 Bauer<\/td><td class=\"column-3\">Tschechien<\/td><td class=\"column-4\">2007\/08, 2009\/10<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Martin Johnsrud Sundby<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2013\/14, 2016<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Alexander Bolshunov<\/td><td class=\"column-3\">Russland<\/td><td class=\"column-4\">2019\/20, 2021<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Tobias Angerer<\/td><td class=\"column-3\">Deutschland<\/td><td class=\"column-4\">2006\/07<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Alexander Legkov<\/td><td class=\"column-3\">Russland<\/td><td class=\"column-4\">2012\/13<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Petter Northug<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2015<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Sergey Ustiugov<\/td><td class=\"column-3\">Russland<\/td><td class=\"column-4\">2016\/17<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">Harald \u00d8stberg Amundsen<\/td><td class=\"column-3\">Norwegen<\/td><td class=\"column-4\">2023\/24<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-120 from cache -->\n<p>Wie es sich f\u00fcr den internationalen Spitzenlanglauf geh\u00f6rt, hei\u00dft die dominierende Nation auch bei der Tour de Ski nat\u00fcrlich Norwegen. Dabei musste das Mutterland des nordischen Skisports nach der ersten Ausgabe des Etappenrennens 2006\/07 ganze sieben Jahre auf den ersten Gesamtsieg warten. Bei der Tour 2013\/14 fuhren die Norweger dann aber sowohl bei den Frauen als auch bei den M\u00e4nnern den totalen Erfolg ein. Zum bislang einzigen Mal in der Geschichte der Tour de Ski belegen hier Athleten aus einem und demselben Land jeweils die ersten drei Positionen der Gesamtwertung!<\/p>\n<p>Die erste Tour de Ski gewann bei den M\u00e4nnern allerdings ein Deutscher. Tobias Angerer triumphierte bei der Premiere, w\u00e4hrend bei den Damen Virpi Kuitunen den ersten Titel holte. Das gleiche Kunstst\u00fcck gelang der Finnin zwei Jahre sp\u00e4ter noch einmal, bevor bei den Frauen die Dominanz von Justyna Kowalczyk begann. Als bislang einzige Athletin gewann sie die Tour de Ski zwischen den Jahren 2009 und 2013 gleich viermal in Folge. Mit vier Titeln zog 2025 dann Therese Johaug, die 2014 als erste Norwegerin die Tour gewann, mit der Polin gleich. Den Titel des Rekordsiegers muss sich die Langlaufnation Nr. 1 ebenfalls teilen. Der geht aktuell n\u00e4mlich nicht nur an Johannes H\u00f8sflot Kl\u00e6bo, sondern auch an den Schweizer Dario Cologna. Der Eidgenosse triumphierte 2009, 2011, 2012 und dann noch einmal 2018. Damit siegten die beiden insgesamt viermal, genau wie Kowalczyk und Johaug.<\/p>\n<p>In zwei weiteren wichtigen Tour de Ski-Kategorien kann Norwegen dann allerdings doch noch alleine gro\u00df auftrumpfen. Mit insgesamt 15 Gesamtsiegen bei M\u00e4nnern und Frauen hat keine Nation das prestigetr\u00e4chtige Etappenrennen so oft gewonnen. Den 2. Platz mit 5 Toursiegen belegt hier Russland, vor der Schweiz und Polen auf dem 3. Rang mit jeweils vier Gesamtsiegen. Unangefochten an der Spitze der Tabelle mit den meisten Etappensiegen (13) in der Geschichte der Tour de Ski liegt bei den M\u00e4nnern mit Petter Northug ebenfalls ein Norweger. Und bei den Damen liegt Therese Johaug mittlerweile mit 16 Etappenerfolgen an der Spitze.<\/p>\n<h2 id=\"faqs-zur-tour-de-ski\">FAQs zur Tour de Ski<\/h2>\n<h3>Wie ist die Tour de Ski entstanden?<\/h3>\n<p>Als V\u00e4ter der Tour de Ski gelten der ehemalige Langlauf-Chef des Weltskiverbandes FIS, J\u00fcrg Capol, und der norwegische Langlauf-Olympiasieger von 1992, Vegard Ulvang. Bei einem gemeinsamen Saunaaufenthalt in Ulvangs Haus in Maridalen sprachen die beiden M\u00e4nner 2004 \u00fcber ein mehrt\u00e4giges Etappenrennen nach dem Vorbild der Tour de France und die M\u00f6glichkeit, dies auch im Langlauf umzusetzen. Ihre Idee kam in den Entscheidungsgremien der FIS so gut an, dass \u00fcber den Jahreswechsel 2006\/07 tats\u00e4chlich die erste Tour de Ski auf die Beine gestellt wurde.<\/p>\n<h3>Wann findet die Tour de Ski statt?<\/h3>\n<p>Die Tour de Ski findet genau wie die Vierschanzentournee der Skispringer immer rund um den Jahreswechsel statt. Das fr\u00fcheste Startdatum einer Tour de Ski war der 27. Dezember 2008, als die erste von sieben Etappen in Oberhof ausgetragen wurde und das letzte Teilst\u00fcck am 4. Januar 2009 im Val die Fiemme geplant war. Dagegen startete die Tour de Ski 2015 am 3. Januar in Oberstdorf so sp\u00e4t wie noch nie. Gleiches galt f\u00fcr die Schlussetappe, die am 10. Januar 2015 als Final Climb auf der Alpe Cermis endete.<\/p>\n<h3>Wo endet die Tour de Ski?<\/h3>\n<p>Seit ihrer ersten Ausgabe 2006\/07 endet die Tour de Ski jedes Mal mit einem einzigartigen Rennen: dem Final Climb. Startpunkt ist dabei immer das Langlaufstadion von Val die Fiemme. Von dort aus verlaufen die erste 5,4 km der 9 km langen Strecke zun\u00e4chst relativ flach, bevor die Loipe schlie\u00dflich nach links abbiegt und dort auch endet. Die letzten 3,6 km sind dann n\u00e4mlich auf der bis zu 28 Prozent steilen Skipiste hinauf zur Alpe Cermis zu bew\u00e4ltigen.<\/p>\n<h3>Wer hat die Tour de Ski am h\u00e4ufigsten gewonnen?<\/h3>\n<p>Rekordsieger der Tour de Ski sind der Schweizer Dario Cologna und der Norweger Johannes H\u00f8sflot Kl\u00e6bo. Die beiden Langlauf-Olympiasieger gewannen jeweils insgesamt vier Ausgaben des Etappenrennens. Cologna in 2008\/09, 2010\/11, 2011\/12 und 2017\/18, Kl\u00e6bo in 2018\/19, 2021\/22, 2022\/23 und 2024\/25. Bei den Damen k\u00f6nnen die Polin Justyna Kowalczyk und die Norwegerin Therese Johaug ebenfalls vier Gesamtsiege bei der Tour de Ski aufweisen. Erstere gewann sie zwischen den Jahren 2009 und 2012 sogar gleich viermal in Folge.<\/p>\n<h3>Welche Orte durchl\u00e4uft die Tour de Ski?<\/h3>\n<p>W\u00e4hrend der Geschichte der Tour de Ski machte das Etappenrennen in insgesamt elf Orten in vier verschiedenen L\u00e4ndern halt. In Deutschland waren es Oberhof, M\u00fcnchen und Oberstdorf, dazu mit Prag und Nov\u00e9 M\u011bsto zwei Stationen in Tschechien sowie drei Stationen in der Schweiz mit Lenzerheide, Val M\u00fcstair und Davos. Italien spielte dann noch in Toblach, Asiago und im Val di Fiemme Gastgeber f\u00fcr mehrere Teilst\u00fccke, wobei das Fleimstal bislang als einziger Etappenort bei jeder einzelnen Tour de Ski-Ausgabe am Start war.<\/p>\n<h3>Wie viele Etappen hat die Tour de Ski?<\/h3>\n<p>Die Tour de Ski wird seit der Saison 2006\/07 im Rahmen des Langlauf-Weltcups ausgetragen. Seitdem schwankte die Anzahl der gelaufenen Etappen zwischen 6 und 9 Etappen. Die meisten Teilst\u00fccke wurden dabei bei der Tour de Ski-Ausgabe 2011\/12 gelaufen, als in Oberhof, Oberstdorf, Toblach und Val die Fiemme insgesamt neun Etappen auf dem Programm standen. Die wenigsten geplanten Etappen gab es bei der Tour de Ski 2021\/22, als insgesamt nur sechs Teilst\u00fccke zu absolvieren waren. Gleiches galt f\u00fcr die Ausgaben 2006\/07 und 2017\/18, wo wegen mehrerer Absagen am Ende ebenfalls nur sechs Etappen gelaufen wurden.<\/p>\n<h3>Was k\u00f6nnen die Athleten bei der Tour de Ski gewinnen?<\/h3>\n<p>F\u00fcr die Skilangl\u00e4uferinnen und Skilangl\u00e4ufer geht es bei der Tour de Ski neben einem Extra-Preisgeld auch um viele Weltcuppunkte. Die Gesamtsieger bei Frauen und M\u00e4nnern erwarten jeweils einen Siegerscheck \u00fcber 80.000 Euro, w\u00e4hrend die Zweitplatzierten jeweils 55.000 Euro und die Drittplatzierten je 40.000 Euro bekommen. Dazu wird ein Etappensieg mit 3.000 Euro belohnt. Auf die Gewinner der Tour de Ski-Gesamtwertung warten zudem noch 300 zus\u00e4tzliche Weltcuppunkte, w\u00e4hrend absteigend bis zum 50. Platz noch 3 Punkte f\u00fcr den Kampf um die gro\u00dfe Kristallkugel ausgelobt sind.<\/p><div id=\"wp-worthy-pixel\"><img decoding=\"async\" class=\"wp-worthy-pixel-img skip-lazy \" src=\"http:\/\/vg07.met.vgwort.de\/na\/b0acb46c98024cc1bc58b10e3dffe5ce\" loading=\"eager\" data-no-lazy=\"1\" data-skip-lazy=\"1\" height=\"1\" width=\"1\" alt=\"\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auf kaum ein zweites Rennen im Langlauf-Weltcup passt das Motto: &#8222;Dies ist ein Marathon, kein Sprint&#8220; so gut wie auf die Tour de Ski. Rund um Neujahr geben die Topathleten des nordischen Skisports hier jedes Jahr auf mehreren Etappen alles. In der letzten Saison demonstrierten dies eindrucksvoll Harald \u00d8stberg Amundsen aus Norwegen und erstmalig die US-Amerikanerin Jessie Diggins. Sie kr\u00f6nten sich am Ende des mittlerweile weltber\u00fchmten Anstiegs zum K\u00f6nig bzw. zur K\u00f6nigin der Langl\u00e4ufer. Grund genug f\u00fcr SnowTrex einmal die Faszination &#8222;Tour de Ski&#8220; zu erkl\u00e4ren und die Sportler vorzustellen, die diesem Wettkampf in der Vergangenheit ihren Stempel aufgedr\u00fcckt haben.<\/p>\n","protected":false},"author":172,"featured_media":52476,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[443],"tags":[1780,17724,17726,17699,17700,17591,2633,2634,2630,17743,17563,7932,17592,17537,2632],"class_list":["post-51662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-event","tag-cavalese","tag-dolomitenregion_3_zinnen","tag-eggental","tag-fassatal","tag-fleimstal","tag-italien","tag-karneid","tag-obereggen","tag-predazzo","tag-provinz_bozen","tag-suedtirol","tag-toblach","tag-trentino","tag-truden","tag-ziano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tour de Ski Etappen 2025\/2026 - Der Langlauf-Klassiker steht an!<\/title>\n<meta name=\"description\" content=\"Die Tour de Ski ist ein Klassiker im Langlauf-Weltcup. Was das Etappen-Event ausmacht und was die Athleten erwartet, erkl\u00e4rt SnowTrex.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Ski 2025\/2026 \u2013 Alle Infos zum Highlight der Skilanglauf-Saison\" \/>\n<meta property=\"og:description\" content=\"Auf kaum ein zweites Rennen im Langlauf-Weltcup passt das Motto: &quot;Dies ist ein Marathon, kein Sprint&quot; so gut wie auf die Tour de Ski. Rund um Neujahr geben die Topathleten des nordischen Skisports hier jedes Jahr auf mehreren Etappen alles. In der letzten Saison demonstrierten dies eindrucksvoll Harald \u00d8stberg Amundsen aus Norwegen und erstmalig die US-Amerikanerin Jessie Diggins. Sie kr\u00f6nten sich am Ende des mittlerweile weltber\u00fchmten Anstiegs zum K\u00f6nig bzw. zur K\u00f6nigin der Langl\u00e4ufer. Grund genug f\u00fcr SnowTrex einmal die Faszination &quot;Tour de Ski&quot; zu erkl\u00e4ren und die Sportler vorzustellen, die diesem Wettkampf in der Vergangenheit ihren Stempel aufgedr\u00fcckt haben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex Ski-Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SnowTrex.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/snowtrex\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-02T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T12:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.snowtrex.de\/magazin\/files\/2023\/11\/51662_Tour_de_Ski.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SnowTrex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SnowTrex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/\"},\"author\":{\"name\":\"SnowTrex\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#\\\/schema\\\/person\\\/d4e6fac722a8050f9a352891795d42d2\"},\"headline\":\"Tour de Ski 2025\\\/2026 \u2013 Alle Infos zum Highlight der Skilanglauf-Saison\",\"datePublished\":\"2025-12-02T00:00:00+00:00\",\"dateModified\":\"2026-05-12T12:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/\"},\"wordCount\":2235,\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2022\\\/12\\\/RS26510_shutterstock_1605515584-hsc.jpg\",\"keywords\":[\"Cavalese\",\"Dolomitenregion 3 Zinnen\",\"Eggental\",\"Fassatal\",\"Fleimstal\",\"Italien\",\"Karneid\",\"Obereggen\",\"Predazzo\",\"Provinz Bozen\",\"S\u00fcdtirol\",\"Toblach\",\"Trentino\",\"Truden\",\"Ziano\"],\"articleSection\":[\"Event\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/\",\"url\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/\",\"name\":\"Tour de Ski Etappen 2025\\\/2026 - Der Langlauf-Klassiker steht an!\",\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2022\\\/12\\\/RS26510_shutterstock_1605515584-hsc.jpg\",\"datePublished\":\"2025-12-02T00:00:00+00:00\",\"dateModified\":\"2026-05-12T12:05:40+00:00\",\"description\":\"Die Tour de Ski ist ein Klassiker im Langlauf-Weltcup. Was das Etappen-Event ausmacht und was die Athleten erwartet, erkl\u00e4rt SnowTrex.\",\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/blog.snowtrex.com\\\/de-magazin\\\/event\\\/tour-de-ski\\\/#primaryimage\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2022\\\/12\\\/RS26510_shutterstock_1605515584-hsc.jpg\",\"contentUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2022\\\/12\\\/RS26510_shutterstock_1605515584-hsc.jpg\",\"width\":1920,\"height\":938},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/\",\"name\":\"SnowTrex Ski-Magazin\",\"description\":\"Alles rund um Skifahren, Snowboarden und Winterurlaub!\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#organization\"},\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"contentUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"width\":1080,\"height\":282,\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SnowTrex.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\"],\"description\":\"Seit 1999 ist SnowTrex Deutschlands f\u00fchrender Reiseveranstalter f\u00fcr Skiurlaub. Das Unternehmen vertreibt seine Angebote in 13 Sprachen und bringt j\u00e4hrlich \u00fcber 100.000 G\u00e4ste in in beliebte Destinationen wie \u00d6sterreich, Frankreich, Italien, die Schweiz und Deutschland.\",\"email\":\"info-de@snowtrex.com\",\"telephone\":\"01806 77 35 00 00\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.de\\\/#\\\/schema\\\/person\\\/d4e6fac722a8050f9a352891795d42d2\",\"name\":\"SnowTrex\",\"description\":\"Die Redaktion des SnowTrex-Magazins vereint erfahrene Wintersportler und Reiseexperten, die ihre Leidenschaft in fundierte Beitr\u00e4ge \u00fcber Skigebiete, Ausr\u00fcstung und Reisetipps einflie\u00dfen lassen. Seit 1999 ist SnowTrex Deutschlands f\u00fchrender Reiseveranstalter f\u00fcr Skiurlaub. Das Unternehmen vertreibt seine Angebote in 13 Sprachen und bringt j\u00e4hrlich \u00fcber 100.000 G\u00e4ste in in beliebte Destinationen wie \u00d6sterreich, Frankreich, Italien, die Schweiz und Deutschland.\",\"sameAs\":[\"https:\\\/\\\/www.snowtrex.de\\\/\",\"https:\\\/\\\/www.facebook.com\\\/snowtrex\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SnowTrex\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de Ski Etappen 2025\/2026 - Der Langlauf-Klassiker steht an!","description":"Die Tour de Ski ist ein Klassiker im Langlauf-Weltcup. Was das Etappen-Event ausmacht und was die Athleten erwartet, erkl\u00e4rt SnowTrex.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/","og_locale":"de_DE","og_type":"article","og_title":"Tour de Ski 2025\/2026 \u2013 Alle Infos zum Highlight der Skilanglauf-Saison","og_description":"Auf kaum ein zweites Rennen im Langlauf-Weltcup passt das Motto: \"Dies ist ein Marathon, kein Sprint\" so gut wie auf die Tour de Ski. Rund um Neujahr geben die Topathleten des nordischen Skisports hier jedes Jahr auf mehreren Etappen alles. In der letzten Saison demonstrierten dies eindrucksvoll Harald \u00d8stberg Amundsen aus Norwegen und erstmalig die US-Amerikanerin Jessie Diggins. Sie kr\u00f6nten sich am Ende des mittlerweile weltber\u00fchmten Anstiegs zum K\u00f6nig bzw. zur K\u00f6nigin der Langl\u00e4ufer. Grund genug f\u00fcr SnowTrex einmal die Faszination \"Tour de Ski\" zu erkl\u00e4ren und die Sportler vorzustellen, die diesem Wettkampf in der Vergangenheit ihren Stempel aufgedr\u00fcckt haben.","og_url":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/","og_site_name":"SnowTrex Ski-Magazin","article_publisher":"https:\/\/www.facebook.com\/SnowTrex.de\/","article_author":"https:\/\/www.facebook.com\/snowtrex\/","article_published_time":"2025-12-02T00:00:00+00:00","article_modified_time":"2026-05-12T12:05:40+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.snowtrex.de\/magazin\/files\/2023\/11\/51662_Tour_de_Ski.jpg","type":"image\/jpeg"}],"author":"SnowTrex","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SnowTrex","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/#article","isPartOf":{"@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/"},"author":{"name":"SnowTrex","@id":"https:\/\/www.snowtrex.de\/magazin\/#\/schema\/person\/d4e6fac722a8050f9a352891795d42d2"},"headline":"Tour de Ski 2025\/2026 \u2013 Alle Infos zum Highlight der Skilanglauf-Saison","datePublished":"2025-12-02T00:00:00+00:00","dateModified":"2026-05-12T12:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/"},"wordCount":2235,"publisher":{"@id":"https:\/\/www.snowtrex.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc.jpg","keywords":["Cavalese","Dolomitenregion 3 Zinnen","Eggental","Fassatal","Fleimstal","Italien","Karneid","Obereggen","Predazzo","Provinz Bozen","S\u00fcdtirol","Toblach","Trentino","Truden","Ziano"],"articleSection":["Event"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/","url":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/","name":"Tour de Ski Etappen 2025\/2026 - Der Langlauf-Klassiker steht an!","primaryImageOfPage":{"@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/#primaryimage"},"image":{"@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc.jpg","datePublished":"2025-12-02T00:00:00+00:00","dateModified":"2026-05-12T12:05:40+00:00","description":"Die Tour de Ski ist ein Klassiker im Langlauf-Weltcup. Was das Etappen-Event ausmacht und was die Athleten erwartet, erkl\u00e4rt SnowTrex.","inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.snowtrex.de\/magazin\/event\/tour-de-ski\/#primaryimage","url":"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc.jpg","contentUrl":"https:\/\/www.snowtrex.de\/magazin\/files\/2022\/12\/RS26510_shutterstock_1605515584-hsc.jpg","width":1920,"height":938},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.de\/magazin\/#website","url":"https:\/\/www.snowtrex.de\/magazin\/","name":"SnowTrex Ski-Magazin","description":"Alles rund um Skifahren, Snowboarden und Winterurlaub!","publisher":{"@id":"https:\/\/www.snowtrex.de\/magazin\/#organization"},"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.de\/magazin\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.snowtrex.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.snowtrex.de\/magazin\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","contentUrl":"https:\/\/www.snowtrex.de\/magazin\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","width":1080,"height":282,"caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SnowTrex.de\/","https:\/\/www.instagram.com\/snowtrex_ski\/"],"description":"Seit 1999 ist SnowTrex Deutschlands f\u00fchrender Reiseveranstalter f\u00fcr Skiurlaub. Das Unternehmen vertreibt seine Angebote in 13 Sprachen und bringt j\u00e4hrlich \u00fcber 100.000 G\u00e4ste in in beliebte Destinationen wie \u00d6sterreich, Frankreich, Italien, die Schweiz und Deutschland.","email":"info-de@snowtrex.com","telephone":"01806 77 35 00 00","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/www.snowtrex.de\/magazin\/#\/schema\/person\/d4e6fac722a8050f9a352891795d42d2","name":"SnowTrex","description":"Die Redaktion des SnowTrex-Magazins vereint erfahrene Wintersportler und Reiseexperten, die ihre Leidenschaft in fundierte Beitr\u00e4ge \u00fcber Skigebiete, Ausr\u00fcstung und Reisetipps einflie\u00dfen lassen. Seit 1999 ist SnowTrex Deutschlands f\u00fchrender Reiseveranstalter f\u00fcr Skiurlaub. Das Unternehmen vertreibt seine Angebote in 13 Sprachen und bringt j\u00e4hrlich \u00fcber 100.000 G\u00e4ste in in beliebte Destinationen wie \u00d6sterreich, Frankreich, Italien, die Schweiz und Deutschland.","sameAs":["https:\/\/www.snowtrex.de\/","https:\/\/www.facebook.com\/snowtrex\/","https:\/\/www.instagram.com\/snowtrex_ski\/","https:\/\/www.youtube.com\/c\/SnowTrex"]}]}},"wp-worthy-pixel":{"ignored":false,"public":"b0acb46c98024cc1bc58b10e3dffe5ce","server":"vg07.met.vgwort.de","url":"http:\/\/vg07.met.vgwort.de\/na\/b0acb46c98024cc1bc58b10e3dffe5ce"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/posts\/51662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/users\/172"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/comments?post=51662"}],"version-history":[{"count":47,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/posts\/51662\/revisions"}],"predecessor-version":[{"id":64245,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/posts\/51662\/revisions\/64245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/media\/52476"}],"wp:attachment":[{"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/media?parent=51662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/categories?post=51662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snowtrex.de\/magazin\/wp-json\/wp\/v2\/tags?post=51662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}